{"id":3078,"count":6,"description":"","link":"https:\/\/scandinavia.life\/lv\/general-topics\/norvegija\/bergena\/","name":"Bergena","slug":"bergena","taxonomy":"category","parent":1639,"meta":[],"_links":{"self":[{"href":"https:\/\/scandinavia.life\/lv\/wp-json\/wp\/v2\/categories\/3078","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/scandinavia.life\/lv\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/scandinavia.life\/lv\/wp-json\/wp\/v2\/taxonomies\/category"}],"up":[{"embeddable":true,"href":"https:\/\/scandinavia.life\/lv\/wp-json\/wp\/v2\/categories\/1639"}],"wp:post_type":[{"href":"https:\/\/scandinavia.life\/lv\/wp-json\/wp\/v2\/posts?categories=3078"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}